{"id":152,"date":"2014-04-11T15:09:04","date_gmt":"2014-04-11T12:09:04","guid":{"rendered":"http:\/\/www.pallokarhut.fi\/lentopallo\/?p=152"},"modified":"2022-03-15T08:33:06","modified_gmt":"2022-03-15T06:33:06","slug":"sisaebiitsiturnaus-1242014-otteluohjelma","status":"publish","type":"post","link":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/","title":{"rendered":"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma"},"content":{"rendered":"<p class=\"MsoNormal\"><strong>KENTT\u00c4 1 <\/strong><\/p>\n<p>\u00a0<\/p>\n<p class=\"MsoNormal\"><strong>OTTELUOHJELMAT JA TULOKSET. KIRJURI MERKITSEE TULOKSET T\u00c4H\u00c4N JA TUO OTTELUP\u00d6YT\u00c4KIRJAN J\u00c4RJESTILLE OTTELUN P\u00c4\u00c4TYTTY\u00c4 (ilmoittautumisp\u00f6yt\u00e4)<\/strong><\/p>\n<table class=\"MsoNormalTable\" style=\"width: 699.0pt; border-collapse: collapse; mso-yfti-tbllook: 1184; mso-table-lspace: 7.05pt; margin-left: 4.8pt; mso-table-rspace: 7.05pt; margin-right: 4.8pt; mso-table-anchor-vertical: page; mso-table-anchor-horizontal: margin; mso-table-left: left; mso-table-top: 135.8pt; mso-padding-alt: 0cm 3.5pt 0cm 3.5pt;\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" width=\"932\" align=\"left\">\n<tbody>\n<tr style=\"mso-yfti-irow: 0; mso-yfti-firstrow: yes; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">kentt\u00e4   1<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">klo<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">SARJA<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">koti<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">vieras<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Ottelutulos<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Er\u00e4pisteet<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">tuomari<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 1; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 2; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">10:20<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NB<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">T\u00f6rm\u00e4nen\/Halme<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Pyykk\u00f6nen\/Kauttio<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kallunki\/Leinonen<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 3; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">11:00<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NB<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">T\u00f6rm\u00e4nen\/Halme<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kallunki\/Leinonen<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Pyykk\u00f6nen\/Kauttio<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 4; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">11:40<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NB<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Mikkonen\/Poutanen<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kallunki\/Leinonen<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">T\u00f6rm\u00e4nen\/Halme<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 5; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">12:20<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NB<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kallunki\/Leinonen<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Pyykk\u00f6nen\/Kauttio<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Mikkonen\/Poutanen<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 6; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">13:00<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NB<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">T\u00f6rm\u00e4nen\/Halme<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Mikkonen\/Poutanen<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kallunki\/Leinonen<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 7; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">13:40<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NB<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Mikkonen\/Poutanen<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Pyykk\u00f6nen\/Kauttio<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">T\u00f6rm\u00e4nen\/Halme<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 8; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">14:20<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NB<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Pronssi   NB<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Sandra<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 9; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">15:00<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NB<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Finaali   NB<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NB   sijoitus 3.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 10; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">15:40<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Finaali   NA<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA   sijoitus 3.<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 11; mso-yfti-lastrow: yes; height: 23.6pt;\">\n<td style=\"width: 52.0pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 70.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"94\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">16:20<\/p>\n<\/td>\n<td style=\"width: 52.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"69\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 112.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"150\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 114.9pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"153\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 63.95pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"85\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 123.55pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"165\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 109.45pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 23.6pt;\" width=\"146\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong>NAISET B-SARJA: JOUKKUEET<\/strong><\/p>\n<p class=\"MsoNormal\"><strong>T\u00f6rm\u00e4nen Ulla \/ Halme P\u00e4ivi\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Mikkonen Roosa \/ Poutanen Petra<\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-size: 11.0pt; line-height: 115%; font-family: &quot;Calibri&quot;,&quot;sans-serif&quot;; mso-ascii-theme-font: minor-latin; mso-fareast-font-family: Calibri; mso-fareast-theme-font: minor-latin; mso-hansi-theme-font: minor-latin; mso-bidi-font-family: &quot;Times New Roman&quot;; mso-bidi-theme-font: minor-bidi; mso-ansi-language: FI; mso-fareast-language: EN-US; mso-bidi-language: AR-SA;\">Kallunki Sara \/ Leinonen Minna \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Pyykk\u00f6nen Pirita \/ Kauttio Heidi<\/span><\/strong><\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong>KENTT\u00c4 2<\/strong><\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong>OTTELUOHJELMAT JA TULOKSET. KIRJURI MERKITSEE TULOKSET T\u00c4H\u00c4N JA TUO OTTELUP\u00d6YT\u00c4KIRJAN J\u00c4RJESTILLE OTTELUN P\u00c4\u00c4TYTTY\u00c4 (ilmoittautumisp\u00f6yt\u00e4)<\/strong><\/p>\n<table class=\"MsoNormalTable\" style=\"width: 753.8pt; border-collapse: collapse; mso-yfti-tbllook: 1184; mso-table-lspace: 7.05pt; margin-left: 4.8pt; mso-table-rspace: 7.05pt; margin-right: 4.8pt; mso-table-anchor-vertical: page; mso-table-anchor-horizontal: margin; mso-table-left: left; mso-table-top: 125.3pt; mso-padding-alt: 0cm 3.5pt 0cm 3.5pt;\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" width=\"1005\" align=\"left\">\n<tbody>\n<tr style=\"mso-yfti-irow: 0; mso-yfti-firstrow: yes; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">kentt\u00e4   2<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">klo<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">SARJA<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">koti<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">vieras<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Ottelutulos<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Er\u00e4pisteet<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">tuomari<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 1; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 2; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">10:20<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA\/1.LOHKO<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Ven\u00e4l\u00e4inen   \/Ven\u00e4l\u00e4inen<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Vilmusenaho\/Tuikkala<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Paulavirta\/Kivel\u00e4<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 3; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">11:00<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA\/1.LOHKO<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Vilmusenaho\/Tuikkala<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Paulavirta\/Kivel\u00e4<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Ven\u00e4l\u00e4inen   \/Ven\u00e4l\u00e4inen<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 4; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">11:40<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA\/1.LOHKO<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Paulavirta\/Kivel\u00e4<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Ven\u00e4l\u00e4inen   \/Ven\u00e4l\u00e4inen<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Vilmusenaho\/Tuikkala<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 5; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">12:20<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">L1\/2<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">L2\/3<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">L1\/1<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 6; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">13:00<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA   (v\u00e4lier\u00e4)<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">L1\/1<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">VOITTAJA   (L1\/2-L2\/3)<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">H\u00c4VI\u00c4J\u00c4   (L1\/2-L2\/3)<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 7; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">13:40<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">(varapaikka   NA-pronssi)<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 8; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">14:20<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">PRONSSI   NA<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Heikkinen\/Kilpel\u00e4inen<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 9; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">15:00<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Rajala\/Kaakinen<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Heikkinen\/Kilpel\u00e4inen<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Sandra<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 10; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">15:40<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Alatalo\/Kangas<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Heikkinen\/Kilpel\u00e4inen<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Sandra<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 11; mso-yfti-lastrow: yes; height: 20.7pt;\">\n<td style=\"width: 50.35pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 50.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"67\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">16:20<\/p>\n<\/td>\n<td style=\"width: 113.3pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"151\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M<\/p>\n<\/td>\n<td style=\"width: 128.0pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"171\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M   FINAALI<\/p>\n<\/td>\n<td style=\"width: 132.2pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"176\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 60.35pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"80\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 98.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"131\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.65pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.7pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Suoma   ja Sandra<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong><br \/><\/strong><\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong>NAISET A-SARJA JOUKKUEET<\/strong><\/p>\n<p class=\"MsoNormal\"><strong>1. LOHKO\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a02. LOHKO<\/strong><\/p>\n<p class=\"MsoNormal\"><strong>Ven\u00e4l\u00e4inen Tuulia \/ Ven\u00e4l\u00e4inen Taisa\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Kaakinen Heidi \/ Kaakinen Sanna<\/strong><\/p>\n<p class=\"MsoNormal\"><strong>Paulavirta Annamari \/ Kivel\u00e4 Anne\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Kumpum\u00e4ki Jaana \/ Korhonen Suoma<\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span style=\"font-size: 11.0pt; line-height: 115%; font-family: &quot;Calibri&quot;,&quot;sans-serif&quot;; mso-ascii-theme-font: minor-latin; mso-fareast-font-family: Calibri; mso-fareast-theme-font: minor-latin; mso-hansi-theme-font: minor-latin; mso-bidi-font-family: &quot;Times New Roman&quot;; mso-bidi-theme-font: minor-bidi; mso-ansi-language: FI; mso-fareast-language: EN-US; mso-bidi-language: AR-SA;\">Vilmusenaho Hanna \/ Tuikkala Leena\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0Tauriainen Noora\/ Ojala Suvi-Tuulia<\/span><\/strong><\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong>KENTT\u00c4 3<\/strong><\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong>OTTELUOHJELMAT JA TULOKSET. KIRJURI MERKITSEE TULOKSET T\u00c4H\u00c4N JA TUO OTTELUP\u00d6YT\u00c4KIRJAN J\u00c4RJESTILLE OTTELUN P\u00c4\u00c4TYTTY\u00c4 (ilmoittautumisp\u00f6yt\u00e4)<\/strong><\/p>\n<table class=\"MsoNormalTable\" style=\"width: 735.05pt; border-collapse: collapse; mso-yfti-tbllook: 1184; mso-table-lspace: 7.05pt; margin-left: 4.8pt; mso-table-rspace: 7.05pt; margin-right: 4.8pt; mso-table-anchor-vertical: page; mso-table-anchor-horizontal: margin; mso-table-left: left; mso-table-top: 141.8pt; mso-padding-alt: 0cm 3.5pt 0cm 3.5pt;\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" width=\"980\" align=\"left\">\n<tbody>\n<tr style=\"mso-yfti-irow: 0; mso-yfti-firstrow: yes; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; mso-border-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">kentt\u00e4   3<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">klo<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">koti<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">vieras<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Ottelutulos<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Er\u00e4pisteet<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border: solid windowtext 1.0pt; border-left: none; mso-border-top-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">tuomari<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 1; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 2; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">10:20<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA\/2.LOHKO<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kaakinen\/Kaakinen<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Tauriainen\/Ojala<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kumpum\u00e4ki\/Korhonen<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 3; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">11:00<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA\/2.LOHKO<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Tauriainen\/Ojala<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kumpum\u00e4ki\/Korhonen<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kaakinen\/Kaakinen<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 4; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">11:40<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA\/2.LOHKO<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kumpum\u00e4ki\/Korhonen<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Kaakinen\/Kaakinen<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Tauriainen\/Ojala<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 5; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">12:20<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">L1\/3<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">L2\/2<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">L2\/1<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 6; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">13:00<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">NA   (v\u00e4lier\u00e4)<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">L2\/1<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">VOITTAJA   (L1\/2-L2\/3)<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">H\u00c4VI\u00c4J\u00c4   (L1\/2-L2\/3)<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 7; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">13:40<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Pitk\u00e4nen\/Haataja<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Heikkinen\/Kilpel\u00e4inen<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Alatalo\/Kangas<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 8; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">14:20<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Alatalo\/Kangas<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Rajala\/Kaakinen<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Pitk\u00e4nen\/Haataja<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 9; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">15:00<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Alatalo\/Kangas<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Pitk\u00e4nen\/Haataja<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Juha<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 10; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">15:40<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Pitk\u00e4nen\/Haataja<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Rajala\/Kaakinen<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Juha<\/p>\n<\/td>\n<\/tr>\n<tr style=\"mso-yfti-irow: 11; mso-yfti-lastrow: yes; height: 20.3pt;\">\n<td style=\"width: 53.25pt; border: solid windowtext 1.0pt; border-top: none; mso-border-left-alt: solid windowtext .5pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 53.25pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"71\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: right;\" align=\"right\">16:20<\/p>\n<\/td>\n<td style=\"width: 72.15pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"96\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M<\/p>\n<\/td>\n<td style=\"width: 122.1pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"163\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">M   PRONSSI<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 77.7pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"104\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 115.4pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"154\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 120.6pt; border-top: none; border-left: none; border-bottom: solid windowtext 1.0pt; border-right: solid windowtext 1.0pt; mso-border-bottom-alt: solid windowtext .5pt; mso-border-right-alt: solid windowtext .5pt; padding: 0cm 3.5pt 0cm 3.5pt; height: 20.3pt;\" width=\"161\" valign=\"bottom\">\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;\">Jaana<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong>MIEHET A-SARJA<\/strong><\/p>\n<p class=\"MsoNormal\"><strong>Alatalo Keijo \/ Kangas Mikko<\/strong><\/p>\n<p class=\"MsoNormal\"><strong>Pitk\u00e4nen Jani \/ Haataja Jani<\/strong><\/p>\n<p class=\"MsoNormal\"><strong>Rajala Isto \/ Kaakinen Marko<\/strong><\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong>Heikkinen Juha \/ Kilpel\u00e4inen Matti<\/strong><\/p>\n<p class=\"MsoNormal\"><strong><br \/><\/strong><\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"><strong><br \/><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>KENTT\u00c4 1 \u00a0 OTTELUOHJELMAT JA TULOKSET. KIRJURI MERKITSEE TULOKSET T\u00c4H\u00c4N JA TUO OTTELUP\u00d6YT\u00c4KIRJAN J\u00c4RJESTILLE OTTELUN P\u00c4\u00c4TYTTY\u00c4 (ilmoittautumisp\u00f6yt\u00e4) kentt\u00e4 1 klo SARJA koti vieras Ottelutulos Er\u00e4pisteet tuomari \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 10:20 NB T\u00f6rm\u00e4nen\/Halme Pyykk\u00f6nen\/Kauttio \u00a0 \u00a0 Kallunki\/Leinonen \u00a0 11:00 NB T\u00f6rm\u00e4nen\/Halme Kallunki\/Leinonen \u00a0 \u00a0 Pyykk\u00f6nen\/Kauttio \u00a0 11:40 NB Mikkonen\/Poutanen Kallunki\/Leinonen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-152","post","type-post","status-publish","format-standard","hentry","category-turnaukset"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma - Pallokarhut, lentopallo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma - Pallokarhut, lentopallo\" \/>\n<meta property=\"og:description\" content=\"KENTT\u00c4 1 \u00a0 OTTELUOHJELMAT JA TULOKSET. KIRJURI MERKITSEE TULOKSET T\u00c4H\u00c4N JA TUO OTTELUP\u00d6YT\u00c4KIRJAN J\u00c4RJESTILLE OTTELUN P\u00c4\u00c4TYTTY\u00c4 (ilmoittautumisp\u00f6yt\u00e4) kentt\u00e4 1 klo SARJA koti vieras Ottelutulos Er\u00e4pisteet tuomari \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 10:20 NB T\u00f6rm\u00e4nen\/Halme Pyykk\u00f6nen\/Kauttio \u00a0 \u00a0 Kallunki\/Leinonen \u00a0 11:00 NB T\u00f6rm\u00e4nen\/Halme Kallunki\/Leinonen \u00a0 \u00a0 Pyykk\u00f6nen\/Kauttio \u00a0 11:40 NB Mikkonen\/Poutanen Kallunki\/Leinonen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/\" \/>\n<meta property=\"og:site_name\" content=\"Pallokarhut, lentopallo\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-11T12:09:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-15T06:33:06+00:00\" \/>\n<meta name=\"author\" content=\"davas_saara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Kirjoittanut\" \/>\n\t<meta name=\"twitter:data1\" content=\"davas_saara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Arvioitu lukuaika\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuuttia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/sisaebiitsiturnaus-1242014-otteluohjelma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/sisaebiitsiturnaus-1242014-otteluohjelma\\\/\"},\"author\":{\"name\":\"davas_saara\",\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/#\\\/schema\\\/person\\\/fe82638390c9ef8ff03f1a83186bf53f\"},\"headline\":\"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma\",\"datePublished\":\"2014-04-11T12:09:04+00:00\",\"dateModified\":\"2022-03-15T06:33:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/sisaebiitsiturnaus-1242014-otteluohjelma\\\/\"},\"wordCount\":400,\"articleSection\":[\"Turnaukset\"],\"inLanguage\":\"fi\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/sisaebiitsiturnaus-1242014-otteluohjelma\\\/\",\"url\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/sisaebiitsiturnaus-1242014-otteluohjelma\\\/\",\"name\":\"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma - Pallokarhut, lentopallo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/#website\"},\"datePublished\":\"2014-04-11T12:09:04+00:00\",\"dateModified\":\"2022-03-15T06:33:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/#\\\/schema\\\/person\\\/fe82638390c9ef8ff03f1a83186bf53f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/sisaebiitsiturnaus-1242014-otteluohjelma\\\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/sisaebiitsiturnaus-1242014-otteluohjelma\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/sisaebiitsiturnaus-1242014-otteluohjelma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/#website\",\"url\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/\",\"name\":\"Pallokarhut, lentopallo\",\"description\":\"Lentopalloa Kuusamossa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/#\\\/schema\\\/person\\\/fe82638390c9ef8ff03f1a83186bf53f\",\"name\":\"davas_saara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/wp-content\\\/litespeed\\\/avatar\\\/f849348f62390ab4d6a206dcd61f5771.jpg?ver=1788201757\",\"url\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/wp-content\\\/litespeed\\\/avatar\\\/f849348f62390ab4d6a206dcd61f5771.jpg?ver=1788201757\",\"contentUrl\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/wp-content\\\/litespeed\\\/avatar\\\/f849348f62390ab4d6a206dcd61f5771.jpg?ver=1788201757\",\"caption\":\"davas_saara\"},\"sameAs\":[\"http:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\"],\"url\":\"https:\\\/\\\/www.pallokarhut.fi\\\/lentopallo\\\/author\\\/davas_saara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma - Pallokarhut, lentopallo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/","og_locale":"fi_FI","og_type":"article","og_title":"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma - Pallokarhut, lentopallo","og_description":"KENTT\u00c4 1 \u00a0 OTTELUOHJELMAT JA TULOKSET. KIRJURI MERKITSEE TULOKSET T\u00c4H\u00c4N JA TUO OTTELUP\u00d6YT\u00c4KIRJAN J\u00c4RJESTILLE OTTELUN P\u00c4\u00c4TYTTY\u00c4 (ilmoittautumisp\u00f6yt\u00e4) kentt\u00e4 1 klo SARJA koti vieras Ottelutulos Er\u00e4pisteet tuomari \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 10:20 NB T\u00f6rm\u00e4nen\/Halme Pyykk\u00f6nen\/Kauttio \u00a0 \u00a0 Kallunki\/Leinonen \u00a0 11:00 NB T\u00f6rm\u00e4nen\/Halme Kallunki\/Leinonen \u00a0 \u00a0 Pyykk\u00f6nen\/Kauttio \u00a0 11:40 NB Mikkonen\/Poutanen Kallunki\/Leinonen [&hellip;]","og_url":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/","og_site_name":"Pallokarhut, lentopallo","article_published_time":"2014-04-11T12:09:04+00:00","article_modified_time":"2022-03-15T06:33:06+00:00","author":"davas_saara","twitter_card":"summary_large_image","twitter_misc":{"Kirjoittanut":"davas_saara","Arvioitu lukuaika":"2 minuuttia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/#article","isPartOf":{"@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/"},"author":{"name":"davas_saara","@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/#\/schema\/person\/fe82638390c9ef8ff03f1a83186bf53f"},"headline":"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma","datePublished":"2014-04-11T12:09:04+00:00","dateModified":"2022-03-15T06:33:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/"},"wordCount":400,"articleSection":["Turnaukset"],"inLanguage":"fi"},{"@type":"WebPage","@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/","url":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/","name":"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma - Pallokarhut, lentopallo","isPartOf":{"@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/#website"},"datePublished":"2014-04-11T12:09:04+00:00","dateModified":"2022-03-15T06:33:06+00:00","author":{"@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/#\/schema\/person\/fe82638390c9ef8ff03f1a83186bf53f"},"breadcrumb":{"@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/sisaebiitsiturnaus-1242014-otteluohjelma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/www.pallokarhut.fi\/lentopallo\/"},{"@type":"ListItem","position":2,"name":"Sis\u00e4biitsiturnaus 12.4.2014 Otteluohjelma"}]},{"@type":"WebSite","@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/#website","url":"https:\/\/www.pallokarhut.fi\/lentopallo\/","name":"Pallokarhut, lentopallo","description":"Lentopalloa Kuusamossa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pallokarhut.fi\/lentopallo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Person","@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/#\/schema\/person\/fe82638390c9ef8ff03f1a83186bf53f","name":"davas_saara","image":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-content\/litespeed\/avatar\/f849348f62390ab4d6a206dcd61f5771.jpg?ver=1788201757","url":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-content\/litespeed\/avatar\/f849348f62390ab4d6a206dcd61f5771.jpg?ver=1788201757","contentUrl":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-content\/litespeed\/avatar\/f849348f62390ab4d6a206dcd61f5771.jpg?ver=1788201757","caption":"davas_saara"},"sameAs":["http:\/\/www.pallokarhut.fi\/lentopallo"],"url":"https:\/\/www.pallokarhut.fi\/lentopallo\/author\/davas_saara\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/posts\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":1,"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/posts\/152\/revisions"}],"predecessor-version":[{"id":1752,"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/posts\/152\/revisions\/1752"}],"wp:attachment":[{"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/media?parent=152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/categories?post=152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pallokarhut.fi\/lentopallo\/wp-json\/wp\/v2\/tags?post=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}